{"id":10349,"date":"2023-07-16T15:35:26","date_gmt":"2023-07-16T07:35:26","guid":{"rendered":"https:\/\/lorentzzi.com\/?p=10349"},"modified":"2025-07-07T10:27:59","modified_gmt":"2025-07-07T02:27:59","slug":"how-many-types-of-timer-relays","status":"publish","type":"post","link":"https:\/\/lorentzzi.com\/fr\/how-many-types-of-timer-relays\/","title":{"rendered":"Combien de types de relais temporis\u00e9s ?"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10349\" class=\"elementor elementor-10349\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca03259 e-flex e-con-boxed e-con e-parent\" data-id=\"ca03259\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ad4203 elementor-widget elementor-widget-text-editor\" data-id=\"1ad4203\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"hover\" data-type=\"2\" data-index=\"1\" data-gid=\"0\">Un relais temporis\u00e9 est un dispositif de commande \u00e9lectrique qui peut contr\u00f4ler la commutation d'un circuit dans un d\u00e9lai sp\u00e9cifique.<\/span>\u00a0<span class=\"\" data-type=\"2\" data-index=\"3\" data-gid=\"1\">Les relais temporis\u00e9s sont largement utilis\u00e9s dans les industries, les m\u00e9nages et les entreprises.<\/span>\u00a0<span class=\"\" data-type=\"2\" data-index=\"5\" data-gid=\"2\">Le principe de base du relais temporis\u00e9 est de convertir le signal \u00e9lectrique en une action m\u00e9canique et de contr\u00f4ler l'interrupteur du circuit par l'interm\u00e9diaire d'un dispositif m\u00e9canique.<\/span>\u00a0<span class=\"\" data-type=\"2\" data-index=\"7\" data-gid=\"5\">Avec les progr\u00e8s constants de la technologie, les types de relais temporis\u00e9s se multiplient \u00e9galement.<\/span>\u00a0Nous pr\u00e9sentons ci-dessous plusieurs types de relais temporis\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-694045b elementor-widget elementor-widget-heading\" data-id=\"694045b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Relais m\u00e9canique \u00e0 temporisation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a73e99b elementor-widget elementor-widget-image\" data-id=\"a73e99b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lorentzzi.com\/fr\/products\/timer-switch-and-counter\/timer\/sul181h-timer-switch\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/mechanical-timer-relay.jpg\" class=\"attachment-large size-large wp-image-10379\" alt=\"relais m\u00e9canique temporis\u00e9\" srcset=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/mechanical-timer-relay.jpg 1024w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/mechanical-timer-relay-300x150.jpg 300w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/mechanical-timer-relay-768x384.jpg 768w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/mechanical-timer-relay-600x300.jpg 600w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/mechanical-timer-relay-64x32.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5651072 elementor-widget elementor-widget-text-editor\" data-id=\"5651072\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"hover\" data-type=\"2\" data-index=\"9\" data-gid=\"6\">Le relais temporis\u00e9 m\u00e9canique est l'un des premiers types de relais temporis\u00e9s.<\/span>\u00a0Ils sont g\u00e9n\u00e9ralement constitu\u00e9s d'engrenages m\u00e9caniques qui tournent ou oscillent pour activer ou d\u00e9sactiver les circuits \u00e9lectriques. Le relais temporis\u00e9 m\u00e9canique pr\u00e9sente les avantages d'une structure simple, d'une grande fiabilit\u00e9 et d'une longue dur\u00e9e de vie. Ils sont largement utilis\u00e9s dans les domaines qui n\u00e9cessitent un contr\u00f4le pr\u00e9cis du temps, tels que les lignes de production automatis\u00e9es, les ascenseurs, les parkings, etc.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce404eb elementor-widget elementor-widget-heading\" data-id=\"ce404eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Relais \u00e9lectronique \u00e0 minuterie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-116f6a1 elementor-widget elementor-widget-image\" data-id=\"116f6a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lorentzzi.com\/fr\/products\/timer-switch-and-counter\/time-delay-relay\/st3pa-time-delay-relay\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Electronic-timer-relay-1.jpg\" class=\"attachment-large size-large wp-image-10386\" alt=\"\" srcset=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Electronic-timer-relay-1.jpg 1024w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Electronic-timer-relay-1-300x150.jpg 300w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Electronic-timer-relay-1-768x384.jpg 768w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Electronic-timer-relay-1-600x300.jpg 600w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Electronic-timer-relay-1-64x32.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c991554 elementor-widget elementor-widget-text-editor\" data-id=\"c991554\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"hover\" data-type=\"2\" data-index=\"13\" data-gid=\"4\">Le relais temporis\u00e9 \u00e9lectronique est un dispositif de contr\u00f4le du temps bas\u00e9 sur des composants \u00e9lectroniques.<\/span>\u00a0Ils utilisent g\u00e9n\u00e9ralement des composants \u00e9lectroniques tels que des circuits int\u00e9gr\u00e9s et des transistors pour contr\u00f4ler la commutation des circuits par le biais de signaux \u00e9lectroniques. Par rapport aux relais temporis\u00e9s m\u00e9caniques, les relais temporis\u00e9s \u00e9lectroniques pr\u00e9sentent les avantages d'une plus grande pr\u00e9cision, d'une plus faible consommation d'\u00e9nergie et d'une vitesse de r\u00e9ponse plus rapide.\u00a0<span class=\"\" data-type=\"2\" data-index=\"15\" data-gid=\"5\">Les relais temporis\u00e9s \u00e9lectroniques sont largement utilis\u00e9s dans les situations qui n\u00e9cessitent un contr\u00f4le de temps de haute pr\u00e9cision, comme les climatiseurs, les commandes d'\u00e9clairage et les distributeurs automatiques.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d852061 elementor-widget elementor-widget-heading\" data-id=\"d852061\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Relais temporis\u00e9 num\u00e9rique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e69b555 elementor-widget elementor-widget-image\" data-id=\"e69b555\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lorentzzi.com\/fr\/products\/timer-switch-and-counter\/timer\/tm619-24-hours-weekly-digital-timer\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/digital-timer-relay.jpg\" class=\"attachment-large size-large wp-image-10396\" alt=\"Relais temporis\u00e9 num\u00e9rique\" srcset=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/digital-timer-relay.jpg 1024w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/digital-timer-relay-300x150.jpg 300w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/digital-timer-relay-768x384.jpg 768w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/digital-timer-relay-600x300.jpg 600w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/digital-timer-relay-64x32.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc2d5bf elementor-widget elementor-widget-text-editor\" data-id=\"bc2d5bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le relais temporis\u00e9 num\u00e9rique est un dispositif de contr\u00f4le du temps bas\u00e9 sur un circuit num\u00e9rique. Ils utilisent g\u00e9n\u00e9ralement des composants num\u00e9riques tels que des circuits int\u00e9gr\u00e9s num\u00e9riques et des microprocesseurs pour contr\u00f4ler la commutation des circuits par le biais de signaux num\u00e9riques. Par rapport aux relais temporis\u00e9s \u00e9lectroniques, les relais temporis\u00e9s num\u00e9riques ont une plus grande programmabilit\u00e9 et flexibilit\u00e9.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08c2208 elementor-widget elementor-widget-heading\" data-id=\"08c2208\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Relais temporis\u00e9 Wifi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3530d2 elementor-widget elementor-widget-image\" data-id=\"b3530d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Non-contact-timer-relay.jpg\" class=\"attachment-large size-large wp-image-10381\" alt=\"relais temporis\u00e9 wifi\" srcset=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Non-contact-timer-relay.jpg 1024w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Non-contact-timer-relay-300x150.jpg 300w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Non-contact-timer-relay-768x384.jpg 768w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Non-contact-timer-relay-600x300.jpg 600w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Non-contact-timer-relay-64x32.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ac0053 elementor-widget elementor-widget-text-editor\" data-id=\"4ac0053\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le relais temporis\u00e9 wifi est un dispositif de contr\u00f4le du temps bas\u00e9 sur la technologie sans fil. Il utilise des signaux sans fil pour contr\u00f4ler la commutation des circuits. Ces relais temporis\u00e9s contr\u00f4l\u00e9s par wifi utilisent g\u00e9n\u00e9ralement la technologie des fr\u00e9quences radio, comme l'infrarouge, le Bluetooth, les fr\u00e9quences radio, etc. Compar\u00e9s \u00e0 d'autres types de relais temporis\u00e9s, ces relais temporis\u00e9s sans contact sont plus s\u00fbrs et plus pratiques, et r\u00e9duisent \u00e9galement les co\u00fbts de c\u00e2blage et d'installation.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa3ae5c elementor-widget elementor-widget-heading\" data-id=\"aa3ae5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Relais temporis\u00e9 multifonctionnel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6d92bd elementor-widget elementor-widget-image\" data-id=\"d6d92bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lorentzzi.com\/fr\/products\/timer-switch-and-counter\/time-delay-relay\/trt-m-multifunctional-time-delay-relay\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Multifunction-timer-relay.jpg\" class=\"attachment-large size-large wp-image-10390\" alt=\"Relais temporis\u00e9 multifonctionnel\" srcset=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Multifunction-timer-relay.jpg 1024w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Multifunction-timer-relay-300x150.jpg 300w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Multifunction-timer-relay-768x384.jpg 768w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Multifunction-timer-relay-600x300.jpg 600w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Multifunction-timer-relay-64x32.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-263e7a8 elementor-widget elementor-widget-text-editor\" data-id=\"263e7a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"hover\" data-type=\"2\" data-index=\"25\" data-gid=\"2\">Les <a href=\"https:\/\/lorentzzi.com\/fr\/products\/timer-switch-and-counter\/time-delay-relay\/trt-m-multifunctional-time-delay-relay\/\"><span style=\"color: #ff0000;\">relais temporis\u00e9 multifonctionnel<\/span><\/a> est un relais temporis\u00e9 avec plusieurs modes de contr\u00f4le (retard \u00e0 l'enclenchement, retard \u00e0 la coupure, coup par coup, cycle de r\u00e9p\u00e9tition, etc.)<\/span>\u00a0Ils peuvent d\u00e9finir diff\u00e9rents modes de contr\u00f4le en fonction de diff\u00e9rents besoins et r\u00e9aliser diverses t\u00e2ches complexes de contr\u00f4le du temps.\u00a0<span class=\"\" data-type=\"2\" data-index=\"27\" data-gid=\"10\">Les relais temporis\u00e9s multifonctionnels sont g\u00e9n\u00e9ralement dot\u00e9s de plusieurs interfaces de signaux d'entr\u00e9e et de sortie et prennent en charge plusieurs m\u00e9thodes de contr\u00f4le, telles que la tension, le courant, la fr\u00e9quence, etc.<\/span>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51ccfaf elementor-widget elementor-widget-heading\" data-id=\"51ccfaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantages et inconv\u00e9nients des diff\u00e9rents types de relais temporis\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6450c1 elementor-widget elementor-widget-image\" data-id=\"d6450c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1a.jpg\" class=\"attachment-large size-large wp-image-10354\" alt=\"Relais temporis\u00e9\" srcset=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1a.jpg 1024w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1a-300x150.jpg 300w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1a-768x384.jpg 768w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1a-600x300.jpg 600w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1a-64x32.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25311fb elementor-widget elementor-widget-text-editor\" data-id=\"25311fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"\" data-type=\"2\" data-index=\"37\" data-gid=\"12\">Qu'il s'agisse d'un relais temporis\u00e9 m\u00e9canique ou d'un relais temporis\u00e9 \u00e9lectronique, tous deux pr\u00e9sentent les avantages d'une structure simple, d'une installation ais\u00e9e et d'un prix peu \u00e9lev\u00e9.<\/span>\u00a0Cependant, ils pr\u00e9sentent \u00e9galement certains inconv\u00e9nients, tels qu'une faible pr\u00e9cision et la possibilit\u00e9 d'\u00eatre facilement affect\u00e9s par des facteurs tels que la temp\u00e9rature et la tension ambiantes.\u00a0<span class=\"\" data-type=\"2\" data-index=\"39\" data-gid=\"5\">Par cons\u00e9quent, dans certains cas n\u00e9cessitant une grande pr\u00e9cision dans le contr\u00f4le du temps, le relais temporis\u00e9 num\u00e9rique est devenu un choix plus appropri\u00e9.<\/span>\u00a0Le relais temporis\u00e9 num\u00e9rique pr\u00e9sente non seulement les avantages d'une grande pr\u00e9cision, d'une bonne fiabilit\u00e9 et d'un contr\u00f4le flexible, mais il peut \u00e9galement d\u00e9finir plusieurs modes de contr\u00f4le par l'interm\u00e9diaire du programme afin de r\u00e9aliser des t\u00e2ches complexes de contr\u00f4le du temps. Les relais temporis\u00e9s num\u00e9riques sont largement utilis\u00e9s dans des domaines tels que l'\u00e9nergie \u00e9lectrique, l'\u00e9lectricit\u00e9, les machines, l'aviation, la m\u00e9tallurgie et la construction.<\/p><p>Le relais temporis\u00e9 sans contact offre une s\u00e9curit\u00e9 et une commodit\u00e9 accrues, tout en r\u00e9duisant les co\u00fbts de c\u00e2blage et d'installation. Les relais temporis\u00e9s sans contact sont largement utilis\u00e9s dans les syst\u00e8mes de contr\u00f4le d'acc\u00e8s \u00e9lectroniques, les commandes d'\u00e9clairage sans fil, les syst\u00e8mes de s\u00e9curit\u00e9, etc.<\/p><p>Le relais temporis\u00e9 multifonction dispose d'une vari\u00e9t\u00e9 de modes de contr\u00f4le, qui peuvent \u00eatre r\u00e9gl\u00e9s en fonction de diff\u00e9rents besoins afin de r\u00e9aliser diverses t\u00e2ches complexes de contr\u00f4le du temps. Les relais temporis\u00e9s multifonctionnels sont largement utilis\u00e9s dans divers domaines n\u00e9cessitant un contr\u00f4le flexible, tels que les \u00e9quipements de r\u00e9frig\u00e9ration, les \u00e9quipements de chauffage, les moteurs, etc.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5049476 elementor-widget elementor-widget-heading\" data-id=\"5049476\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conclusion<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a20a9d elementor-widget elementor-widget-text-editor\" data-id=\"6a20a9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En bref, les relais temporis\u00e9s jouent un r\u00f4le tr\u00e8s important dans l'industrie moderne. En choisissant un relais temporis\u00e9 appropri\u00e9, il est possible d'obtenir un contr\u00f4le pr\u00e9cis du circuit, d'am\u00e9liorer l'efficacit\u00e9 de la production, de r\u00e9duire la consommation d'\u00e9nergie, de r\u00e9duire la main-d'\u0153uvre et de rendre le processus de production plus intelligent et automatis\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>A timer relay is an electrical control device that can control the switching of a circuit within a specific time.\u00a0Timer relays are widely used in industries, households and businesses.\u00a0The basic principle of the timer relay is to convert the electrical signal into a mechanical action, and control the switch of the circuit through a mechanical [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10351,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[123],"tags":[],"class_list":["post-10349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-time-delay-relay"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>How Many Types Of Timer Relays?<\/title>\n<meta name=\"description\" content=\"There are at least 5 types of time relays in the market, so what is their differences? how to use them, let me explain them for you.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lorentzzi.com\/fr\/how-many-types-of-timer-relays\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How Many Types Of Timer Relays?\" \/>\n<meta property=\"og:description\" content=\"There are at least 5 types of time relays in the market, so what is their differences? how to use them, let me explain them for you.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lorentzzi.com\/fr\/how-many-types-of-timer-relays\/\" \/>\n<meta property=\"og:site_name\" content=\"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-16T07:35:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T02:27:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Shon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Shon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/\"},\"author\":{\"name\":\"Shon\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#\\\/schema\\\/person\\\/f4d29474f9d489167c3db9a85835c8d1\"},\"headline\":\"How Many Types Of Timer Relays?\",\"datePublished\":\"2023-07-16T07:35:26+00:00\",\"dateModified\":\"2025-07-07T02:27:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/\"},\"wordCount\":669,\"publisher\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lorentzzi.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Time-delay-relay-1.jpg\",\"articleSection\":[\"Time Delay Relay\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/\",\"url\":\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/\",\"name\":\"How Many Types Of Timer Relays?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lorentzzi.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Time-delay-relay-1.jpg\",\"datePublished\":\"2023-07-16T07:35:26+00:00\",\"dateModified\":\"2025-07-07T02:27:59+00:00\",\"description\":\"There are at least 5 types of time relays in the market, so what is their differences? how to use them, let me explain them for you.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lorentzzi.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Time-delay-relay-1.jpg\",\"contentUrl\":\"https:\\\/\\\/lorentzzi.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Time-delay-relay-1.jpg\",\"width\":640,\"height\":640,\"caption\":\"Types of time delay relays\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/how-many-types-of-timer-relays\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lorentzzi.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How Many Types Of Timer Relays?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#website\",\"url\":\"https:\\\/\\\/lorentzzi.com\\\/\",\"name\":\"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter\",\"description\":\"Lorentzzi supply temperature controller, SSR, proximity sensor, SCR power regulator and timer switch with good quality and affordable prices.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lorentzzi.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#organization\",\"name\":\"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter\",\"url\":\"https:\\\/\\\/lorentzzi.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lorentzzi.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Lorenz-Electric-Company-Logo.png\",\"contentUrl\":\"https:\\\/\\\/lorentzzi.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Lorenz-Electric-Company-Logo.png\",\"width\":350,\"height\":100,\"caption\":\"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter\"},\"image\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#\\\/schema\\\/person\\\/f4d29474f9d489167c3db9a85835c8d1\",\"name\":\"Shon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f69dc284c47c894ea65337e116c60f9631c41384716996703e24a1655bca115?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f69dc284c47c894ea65337e116c60f9631c41384716996703e24a1655bca115?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2f69dc284c47c894ea65337e116c60f9631c41384716996703e24a1655bca115?s=96&d=mm&r=g\",\"caption\":\"Shon\"},\"sameAs\":[\"https:\\\/\\\/lorentzzi.com\"],\"url\":\"https:\\\/\\\/lorentzzi.com\\\/fr\\\/author\\\/shon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Combien de types de relais temporis\u00e9s ?","description":"Il existe au moins 5 types de relais temporis\u00e9s sur le march\u00e9. Quelles sont leurs diff\u00e9rences ? Comment les utiliser ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lorentzzi.com\/fr\/how-many-types-of-timer-relays\/","og_locale":"fr_FR","og_type":"article","og_title":"How Many Types Of Timer Relays?","og_description":"There are at least 5 types of time relays in the market, so what is their differences? how to use them, let me explain them for you.","og_url":"https:\/\/lorentzzi.com\/fr\/how-many-types-of-timer-relays\/","og_site_name":"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter","article_published_time":"2023-07-16T07:35:26+00:00","article_modified_time":"2025-07-07T02:27:59+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1.jpg","type":"image\/jpeg"}],"author":"Shon","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Shon","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/#article","isPartOf":{"@id":"https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/"},"author":{"name":"Shon","@id":"https:\/\/lorentzzi.com\/#\/schema\/person\/f4d29474f9d489167c3db9a85835c8d1"},"headline":"How Many Types Of Timer Relays?","datePublished":"2023-07-16T07:35:26+00:00","dateModified":"2025-07-07T02:27:59+00:00","mainEntityOfPage":{"@id":"https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/"},"wordCount":669,"publisher":{"@id":"https:\/\/lorentzzi.com\/#organization"},"image":{"@id":"https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/#primaryimage"},"thumbnailUrl":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1.jpg","articleSection":["Time Delay Relay"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/","url":"https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/","name":"Combien de types de relais temporis\u00e9s ?","isPartOf":{"@id":"https:\/\/lorentzzi.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/#primaryimage"},"image":{"@id":"https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/#primaryimage"},"thumbnailUrl":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1.jpg","datePublished":"2023-07-16T07:35:26+00:00","dateModified":"2025-07-07T02:27:59+00:00","description":"Il existe au moins 5 types de relais temporis\u00e9s sur le march\u00e9. Quelles sont leurs diff\u00e9rences ? Comment les utiliser ?","breadcrumb":{"@id":"https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/#primaryimage","url":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1.jpg","contentUrl":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/07\/Time-delay-relay-1.jpg","width":640,"height":640,"caption":"Types of time delay relays"},{"@type":"BreadcrumbList","@id":"https:\/\/lorentzzi.com\/how-many-types-of-timer-relays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lorentzzi.com\/"},{"@type":"ListItem","position":2,"name":"How Many Types Of Timer Relays?"}]},{"@type":"WebSite","@id":"https:\/\/lorentzzi.com\/#website","url":"https:\/\/lorentzzi.com\/","name":"Lorentzzi Industrial Supply - Fabricant et exportateur chinois","description":"Lorentzzi fournit des r\u00e9gulateurs de temp\u00e9rature, des SSR, des capteurs de proximit\u00e9, des r\u00e9gulateurs de puissance SCR et des interrupteurs temporis\u00e9s de bonne qualit\u00e9 et \u00e0 des prix abordables.","publisher":{"@id":"https:\/\/lorentzzi.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lorentzzi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lorentzzi.com\/#organization","name":"Lorentzzi Industrial Supply - Fabricant et exportateur chinois","url":"https:\/\/lorentzzi.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lorentzzi.com\/#\/schema\/logo\/image\/","url":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2021\/07\/Lorenz-Electric-Company-Logo.png","contentUrl":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2021\/07\/Lorenz-Electric-Company-Logo.png","width":350,"height":100,"caption":"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter"},"image":{"@id":"https:\/\/lorentzzi.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/lorentzzi.com\/#\/schema\/person\/f4d29474f9d489167c3db9a85835c8d1","name":"Shon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/2f69dc284c47c894ea65337e116c60f9631c41384716996703e24a1655bca115?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2f69dc284c47c894ea65337e116c60f9631c41384716996703e24a1655bca115?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f69dc284c47c894ea65337e116c60f9631c41384716996703e24a1655bca115?s=96&d=mm&r=g","caption":"Shon"},"sameAs":["https:\/\/lorentzzi.com"],"url":"https:\/\/lorentzzi.com\/fr\/author\/shon\/"}]}},"_links":{"self":[{"href":"https:\/\/lorentzzi.com\/fr\/wp-json\/wp\/v2\/posts\/10349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lorentzzi.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lorentzzi.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lorentzzi.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lorentzzi.com\/fr\/wp-json\/wp\/v2\/comments?post=10349"}],"version-history":[{"count":35,"href":"https:\/\/lorentzzi.com\/fr\/wp-json\/wp\/v2\/posts\/10349\/revisions"}],"predecessor-version":[{"id":10406,"href":"https:\/\/lorentzzi.com\/fr\/wp-json\/wp\/v2\/posts\/10349\/revisions\/10406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lorentzzi.com\/fr\/wp-json\/wp\/v2\/media\/10351"}],"wp:attachment":[{"href":"https:\/\/lorentzzi.com\/fr\/wp-json\/wp\/v2\/media?parent=10349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lorentzzi.com\/fr\/wp-json\/wp\/v2\/categories?post=10349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lorentzzi.com\/fr\/wp-json\/wp\/v2\/tags?post=10349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}