{"id":7759,"date":"2023-04-10T21:52:09","date_gmt":"2023-04-10T13:52:09","guid":{"rendered":"https:\/\/lorentzzi.com\/?post_type=product&#038;p=7759"},"modified":"2025-12-27T13:14:01","modified_gmt":"2025-12-27T05:14:01","slug":"diffuse-photoelectric-sensor","status":"publish","type":"product","link":"https:\/\/lorentzzi.com\/es\/products\/proximity-sensor\/photoelectric-sensor\/diffuse-photoelectric-sensor\/","title":{"rendered":"Barrera fotoel\u00e9ctrica difusa"},"content":{"rendered":"<h2><strong>Diffuse Photoelectric Sensor Introduction:<\/strong><\/h2>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">The working principle of the diffuse photoelectric sensor is based on the diffuse reflection of light. We know that there is an intensity difference between reflected and emitted light. Diffuse sensors use this difference to determine whether an object is present.<\/span><\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-13019\" src=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/04\/Diffuse-photoelectric-sensor-description.png\" alt=\"Diffuse photoelectric sensor description\" width=\"846\" height=\"241\" srcset=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/04\/Diffuse-photoelectric-sensor-description.png 421w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/04\/Diffuse-photoelectric-sensor-description-300x86.png 300w, https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/04\/Diffuse-photoelectric-sensor-description-64x18.png 64w\" sizes=\"(max-width: 846px) 100vw, 846px\" \/><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">This diffuse photoelectric sensor is our G25 model proximity switch, which uses the infrared light reflected back from the object to detect the presence or absence of the object.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">This G25 diffuse reflection photoelectric sensor has a maximum detection distance of 70.0 cm and is suitable for any kind of material, whether the object is conductor such as iron, aluminum, steel or insulator like glass, wood, plastic, ceramics, etc.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">The housing of the G25 sensor is made of solid ABS material, which can withstand high temperatures and is fire-resistant.<\/span><\/li>\n<\/ul>\n<h2><strong>Specifications:<\/strong><\/h2>\n<div class=\"supsystic-table-loader spinner\"style=\"background-color:#000000\"><\/div><div id=\"supsystic-table-98_32417\" class=\"supsystic-tables-wrap \" style=\" width:100%; visibility: hidden; \" data-table-width-fixed=\"100%\" data-table-width-mobile=\"100%\" ><table id=\"supsystic-table-98\" class=\"supsystic-table border lightboxImg cell-border\" data-id=\"98\" data-view-id=\"98_32417\" data-title=\"G25\" data-currency-format=\"$1,000.00\" data-percent-format=\"10.00%\" data-date-format=\"DD.MM.YYYY\" data-time-format=\"HH:mm\" data-features=\"[&quot;after_table_loaded_script&quot;]\" data-search-value=\"\" data-lightbox-img=\"\" data-head-rows-count=\"1\" data-pagination-length=\"50,100,All\" data-auto-index=\"off\" data-searching-settings=\"{&quot;columnSearchPosition&quot;:&quot;bottom&quot;,&quot;minChars&quot;:&quot;0&quot;}\" data-lang=\"default\" data-override=\"{&quot;emptyTable&quot;:&quot;&quot;,&quot;info&quot;:&quot;&quot;,&quot;infoEmpty&quot;:&quot;&quot;,&quot;infoFiltered&quot;:&quot;&quot;,&quot;lengthMenu&quot;:&quot;&quot;,&quot;search&quot;:&quot;&quot;,&quot;zeroRecords&quot;:&quot;&quot;,&quot;exportLabel&quot;:&quot;&quot;,&quot;file&quot;:&quot;default&quot;}\" data-merged=\"[{&quot;row&quot;:0,&quot;col&quot;:0,&quot;rowspan&quot;:10,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:10,&quot;col&quot;:0,&quot;rowspan&quot;:10,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:20,&quot;col&quot;:0,&quot;rowspan&quot;:10,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:0,&quot;col&quot;:1,&quot;rowspan&quot;:1,&quot;colspan&quot;:3,&quot;removed&quot;:false},{&quot;row&quot;:10,&quot;col&quot;:1,&quot;rowspan&quot;:1,&quot;colspan&quot;:3,&quot;removed&quot;:false},{&quot;row&quot;:20,&quot;col&quot;:1,&quot;rowspan&quot;:1,&quot;colspan&quot;:3,&quot;removed&quot;:false},{&quot;row&quot;:1,&quot;col&quot;:2,&quot;rowspan&quot;:3,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:4,&quot;col&quot;:2,&quot;rowspan&quot;:3,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:1,&quot;col&quot;:1,&quot;rowspan&quot;:6,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:7,&quot;col&quot;:1,&quot;rowspan&quot;:3,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:7,&quot;col&quot;:2,&quot;rowspan&quot;:2,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:11,&quot;col&quot;:1,&quot;rowspan&quot;:6,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:17,&quot;col&quot;:1,&quot;rowspan&quot;:3,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:11,&quot;col&quot;:2,&quot;rowspan&quot;:3,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:14,&quot;col&quot;:2,&quot;rowspan&quot;:3,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:17,&quot;col&quot;:2,&quot;rowspan&quot;:2,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:21,&quot;col&quot;:1,&quot;rowspan&quot;:6,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:27,&quot;col&quot;:1,&quot;rowspan&quot;:3,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:21,&quot;col&quot;:2,&quot;rowspan&quot;:3,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:24,&quot;col&quot;:2,&quot;rowspan&quot;:3,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:27,&quot;col&quot;:2,&quot;rowspan&quot;:2,&quot;colspan&quot;:1,&quot;removed&quot;:false},{&quot;row&quot;:30,&quot;col&quot;:0,&quot;rowspan&quot;:1,&quot;colspan&quot;:4,&quot;removed&quot;:false},{&quot;row&quot;:31,&quot;col&quot;:0,&quot;rowspan&quot;:1,&quot;colspan&quot;:4,&quot;removed&quot;:false},{&quot;row&quot;:32,&quot;col&quot;:0,&quot;rowspan&quot;:1,&quot;colspan&quot;:4,&quot;removed&quot;:false},{&quot;row&quot;:33,&quot;col&quot;:0,&quot;rowspan&quot;:1,&quot;colspan&quot;:4,&quot;removed&quot;:false},{&quot;row&quot;:34,&quot;col&quot;:0,&quot;rowspan&quot;:1,&quot;colspan&quot;:4,&quot;removed&quot;:false},{&quot;row&quot;:35,&quot;col&quot;:0,&quot;rowspan&quot;:1,&quot;colspan&quot;:4,&quot;removed&quot;:false},{&quot;row&quot;:36,&quot;col&quot;:0,&quot;rowspan&quot;:1,&quot;colspan&quot;:4,&quot;removed&quot;:false},{&quot;row&quot;:37,&quot;col&quot;:0,&quot;rowspan&quot;:1,&quot;colspan&quot;:4,&quot;removed&quot;:false},{&quot;row&quot;:38,&quot;col&quot;:0,&quot;rowspan&quot;:1,&quot;colspan&quot;:4,&quot;removed&quot;:false},{&quot;row&quot;:9,&quot;col&quot;:2,&quot;rowspan&quot;:1,&quot;colspan&quot;:2,&quot;removed&quot;:false},{&quot;row&quot;:19,&quot;col&quot;:2,&quot;rowspan&quot;:1,&quot;colspan&quot;:2,&quot;removed&quot;:false},{&quot;row&quot;:29,&quot;col&quot;:2,&quot;rowspan&quot;:1,&quot;colspan&quot;:2,&quot;removed&quot;:false}]\" data-responsive-mode=\"0\" data-from-history=\"0\" ><thead><tr><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><th class=\"\" style=\"width:; padding: 0 !important;\"><\/th><\/tr><\/thead><tbody><tr style=\"height:px\" ><td data-cell-id=\"A1\" data-x=\"0\" data-y=\"1\" data-db-index=\"1\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"Diffuse type\" data-order=\"Diffuse type\" style=\"min-width:17.236%; \" data-colspan=\"1\" data-rowspan=\"10\" >Diffuse type <\/td><td data-cell-id=\"B1\" data-x=\"1\" data-y=\"1\" data-db-index=\"1\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"Detection distance\" data-order=\"Detection distance\" style=\"min-width:15.6832%; \" data-colspan=\"3\" data-rowspan=\"1\" >Detection distance <\/td><td data-cell-id=\"C1\" data-x=\"2\" data-y=\"1\" data-db-index=\"1\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" style=\"min-width:19.2547%; \" data-hide=\"true\" ><\/td><td data-cell-id=\"D1\" data-x=\"3\" data-y=\"1\" data-db-index=\"1\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" style=\"min-width:16.3043%; \" data-hide=\"true\" ><\/td><td data-cell-id=\"E1\" data-x=\"4\" data-y=\"1\" data-db-index=\"1\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"70cm\" data-order=\"70cm\" style=\"min-width:31.5217%; \" >70cm <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A2\" data-x=\"0\" data-y=\"2\" data-db-index=\"2\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B2\" data-x=\"1\" data-y=\"2\" data-db-index=\"2\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"10-30VDC\" data-order=\"10-30VDC\" data-colspan=\"1\" data-rowspan=\"6\" >10-30VDC <\/td><td data-cell-id=\"C2\" data-x=\"2\" data-y=\"2\" data-db-index=\"2\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NPN\" data-order=\"NPN\" data-colspan=\"1\" data-rowspan=\"3\" >NPN <\/td><td data-cell-id=\"D2\" data-x=\"3\" data-y=\"2\" data-db-index=\"2\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NO\" data-order=\"NO\" >NO <\/td><td data-cell-id=\"E2\" data-x=\"4\" data-y=\"2\" data-db-index=\"2\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-3A70NA\" data-order=\"G25-3A70NA\" >G25-3A70NA <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A3\" data-x=\"0\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B3\" data-x=\"1\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C3\" data-x=\"2\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D3\" data-x=\"3\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NC\" data-order=\"NC\" >NC <\/td><td data-cell-id=\"E3\" data-x=\"4\" data-y=\"3\" data-db-index=\"3\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-3A70NB\" data-order=\"G25-3A70NB\" >G25-3A70NB <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A4\" data-x=\"0\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B4\" data-x=\"1\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C4\" data-x=\"2\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D4\" data-x=\"3\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NO+NC\" data-order=\"NO+NC\" >NO+NC <\/td><td data-cell-id=\"E4\" data-x=\"4\" data-y=\"4\" data-db-index=\"4\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-3A70NC\" data-order=\"G25-3A70NC\" >G25-3A70NC <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A5\" data-x=\"0\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B5\" data-x=\"1\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C5\" data-x=\"2\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"PNP\" data-order=\"PNP\" data-colspan=\"1\" data-rowspan=\"3\" >PNP <\/td><td data-cell-id=\"D5\" data-x=\"3\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NO\" data-order=\"NO\" >NO <\/td><td data-cell-id=\"E5\" data-x=\"4\" data-y=\"5\" data-db-index=\"5\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-3A70PA\" data-order=\"G25-3A70PA\" >G25-3A70PA <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A6\" data-x=\"0\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B6\" data-x=\"1\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C6\" data-x=\"2\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D6\" data-x=\"3\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NC\" data-order=\"NC\" >NC <\/td><td data-cell-id=\"E6\" data-x=\"4\" data-y=\"6\" data-db-index=\"6\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-3A70PB\" data-order=\"G25-3A70PB\" >G25-3A70PB <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A7\" data-x=\"0\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B7\" data-x=\"1\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C7\" data-x=\"2\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D7\" data-x=\"3\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NO+NC\" data-order=\"NO+NC\" >NO+NC <\/td><td data-cell-id=\"E7\" data-x=\"4\" data-y=\"7\" data-db-index=\"7\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-3A70PC\" data-order=\"G25-3A70PC\" >G25-3A70PC <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A8\" data-x=\"0\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B8\" data-x=\"1\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"90-250VAC\" data-order=\"90-250VAC\" data-colspan=\"1\" data-rowspan=\"3\" >90-250VAC <\/td><td data-cell-id=\"C8\" data-x=\"2\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"Control lable silicon\" data-order=\"Control lable silicon\" data-colspan=\"1\" data-rowspan=\"2\" >Control lable silicon <\/td><td data-cell-id=\"D8\" data-x=\"3\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NO\" data-order=\"NO\" >NO <\/td><td data-cell-id=\"E8\" data-x=\"4\" data-y=\"8\" data-db-index=\"8\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-2A70LA\" data-order=\"G25-2A70LA\" >G25-2A70LA <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A9\" data-x=\"0\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B9\" data-x=\"1\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C9\" data-x=\"2\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D9\" data-x=\"3\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NC\" data-order=\"NC\" >NC <\/td><td data-cell-id=\"E9\" data-x=\"4\" data-y=\"9\" data-db-index=\"9\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-2A70LB\" data-order=\"G25-2A70LB\" >G25-2A70LB <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A10\" data-x=\"0\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B10\" data-x=\"1\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C10\" data-x=\"2\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"Relay output\" data-order=\"Relay output\" data-colspan=\"2\" data-rowspan=\"1\" >Relay output <\/td><td data-cell-id=\"D10\" data-x=\"3\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E10\" data-x=\"4\" data-y=\"10\" data-db-index=\"10\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-2A70JC\" data-order=\"G25-2A70JC\" >G25-2A70JC <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A11\" data-x=\"0\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"Retroreflective\" data-order=\"Retroreflective\" data-colspan=\"1\" data-rowspan=\"10\" >Retroreflective <\/td><td data-cell-id=\"B11\" data-x=\"1\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"Detection distance\" data-order=\"Detection distance\" data-colspan=\"3\" data-rowspan=\"1\" >Detection distance <\/td><td data-cell-id=\"C11\" data-x=\"2\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D11\" data-x=\"3\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E11\" data-x=\"4\" data-y=\"11\" data-db-index=\"11\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"4m\" data-order=\"4m\" >4m <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A12\" data-x=\"0\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B12\" data-x=\"1\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"10-30VDC\" data-order=\"10-30VDC\" data-colspan=\"1\" data-rowspan=\"6\" >10-30VDC <\/td><td data-cell-id=\"C12\" data-x=\"2\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NPN\" data-order=\"NPN\" data-colspan=\"1\" data-rowspan=\"3\" >NPN <\/td><td data-cell-id=\"D12\" data-x=\"3\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NO\" data-order=\"NO\" >NO <\/td><td data-cell-id=\"E12\" data-x=\"4\" data-y=\"12\" data-db-index=\"12\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-3B4NA\" data-order=\"G25-3B4NA\" >G25-3B4NA <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A13\" data-x=\"0\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B13\" data-x=\"1\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C13\" data-x=\"2\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D13\" data-x=\"3\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NC\" data-order=\"NC\" >NC <\/td><td data-cell-id=\"E13\" data-x=\"4\" data-y=\"13\" data-db-index=\"13\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-3B4NB\" data-order=\"G25-3B4NB\" >G25-3B4NB <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A14\" data-x=\"0\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B14\" data-x=\"1\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C14\" data-x=\"2\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D14\" data-x=\"3\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NO+NC\" data-order=\"NO+NC\" >NO+NC <\/td><td data-cell-id=\"E14\" data-x=\"4\" data-y=\"14\" data-db-index=\"14\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-3B4NC\" data-order=\"G25-3B4NC\" >G25-3B4NC <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A15\" data-x=\"0\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B15\" data-x=\"1\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C15\" data-x=\"2\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"PNP\" data-order=\"PNP\" data-colspan=\"1\" data-rowspan=\"3\" >PNP <\/td><td data-cell-id=\"D15\" data-x=\"3\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NO\" data-order=\"NO\" >NO <\/td><td data-cell-id=\"E15\" data-x=\"4\" data-y=\"15\" data-db-index=\"15\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-3B4PA\" data-order=\"G25-3B4PA\" >G25-3B4PA <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A16\" data-x=\"0\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B16\" data-x=\"1\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C16\" data-x=\"2\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D16\" data-x=\"3\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NC\" data-order=\"NC\" >NC <\/td><td data-cell-id=\"E16\" data-x=\"4\" data-y=\"16\" data-db-index=\"16\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-3B4PB\" data-order=\"G25-3B4PB\" >G25-3B4PB <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A17\" data-x=\"0\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B17\" data-x=\"1\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C17\" data-x=\"2\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D17\" data-x=\"3\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NO+NC\" data-order=\"NO+NC\" >NO+NC <\/td><td data-cell-id=\"E17\" data-x=\"4\" data-y=\"17\" data-db-index=\"17\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-3B4PC\" data-order=\"G25-3B4PC\" >G25-3B4PC <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A18\" data-x=\"0\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B18\" data-x=\"1\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"90-250VAC\" data-order=\"90-250VAC\" data-colspan=\"1\" data-rowspan=\"3\" >90-250VAC <\/td><td data-cell-id=\"C18\" data-x=\"2\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"Controllable silicon\" data-order=\"Controllable silicon\" data-colspan=\"1\" data-rowspan=\"2\" >Controllable silicon <\/td><td data-cell-id=\"D18\" data-x=\"3\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NO\" data-order=\"NO\" >NO <\/td><td data-cell-id=\"E18\" data-x=\"4\" data-y=\"18\" data-db-index=\"18\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-2B4LA\" data-order=\"G25-2B4LA\" >G25-2B4LA <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A19\" data-x=\"0\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B19\" data-x=\"1\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C19\" data-x=\"2\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D19\" data-x=\"3\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NC\" data-order=\"NC\" >NC <\/td><td data-cell-id=\"E19\" data-x=\"4\" data-y=\"19\" data-db-index=\"19\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-2B4LB\" data-order=\"G25-2B4LB\" >G25-2B4LB <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A20\" data-x=\"0\" data-y=\"20\" data-db-index=\"20\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B20\" data-x=\"1\" data-y=\"20\" data-db-index=\"20\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C20\" data-x=\"2\" data-y=\"20\" data-db-index=\"20\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"Relay output\" data-order=\"Relay output\" data-colspan=\"2\" data-rowspan=\"1\" >Relay output <\/td><td data-cell-id=\"D20\" data-x=\"3\" data-y=\"20\" data-db-index=\"20\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E20\" data-x=\"4\" data-y=\"20\" data-db-index=\"20\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-2B4JC\" data-order=\"G25-2B4JC\" >G25-2B4JC <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A21\" data-x=\"0\" data-y=\"21\" data-db-index=\"21\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"Through-beam\" data-order=\"Through-beam\" data-colspan=\"1\" data-rowspan=\"10\" >Through-beam <\/td><td data-cell-id=\"B21\" data-x=\"1\" data-y=\"21\" data-db-index=\"21\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"Detection distance\" data-order=\"Detection distance\" data-colspan=\"3\" data-rowspan=\"1\" >Detection distance <\/td><td data-cell-id=\"C21\" data-x=\"2\" data-y=\"21\" data-db-index=\"21\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D21\" data-x=\"3\" data-y=\"21\" data-db-index=\"21\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E21\" data-x=\"4\" data-y=\"21\" data-db-index=\"21\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"7m\" data-order=\"7m\" >7m <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A22\" data-x=\"0\" data-y=\"22\" data-db-index=\"22\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B22\" data-x=\"1\" data-y=\"22\" data-db-index=\"22\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"10-30VDC\" data-order=\"10-30VDC\" data-colspan=\"1\" data-rowspan=\"6\" >10-30VDC <\/td><td data-cell-id=\"C22\" data-x=\"2\" data-y=\"22\" data-db-index=\"22\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NPN\" data-order=\"NPN\" data-colspan=\"1\" data-rowspan=\"3\" >NPN <\/td><td data-cell-id=\"D22\" data-x=\"3\" data-y=\"22\" data-db-index=\"22\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NO\" data-order=\"NO\" >NO <\/td><td data-cell-id=\"E22\" data-x=\"4\" data-y=\"22\" data-db-index=\"22\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-3C7NA\" data-order=\"G25-3C7NA\" >G25-3C7NA <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A23\" data-x=\"0\" data-y=\"23\" data-db-index=\"23\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B23\" data-x=\"1\" data-y=\"23\" data-db-index=\"23\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C23\" data-x=\"2\" data-y=\"23\" data-db-index=\"23\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D23\" data-x=\"3\" data-y=\"23\" data-db-index=\"23\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NC\" data-order=\"NC\" >NC <\/td><td data-cell-id=\"E23\" data-x=\"4\" data-y=\"23\" data-db-index=\"23\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-3C7NB\" data-order=\"G25-3C7NB\" >G25-3C7NB <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A24\" data-x=\"0\" data-y=\"24\" data-db-index=\"24\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B24\" data-x=\"1\" data-y=\"24\" data-db-index=\"24\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C24\" data-x=\"2\" data-y=\"24\" data-db-index=\"24\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D24\" data-x=\"3\" data-y=\"24\" data-db-index=\"24\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NO+NC\" data-order=\"NO+NC\" >NO+NC <\/td><td data-cell-id=\"E24\" data-x=\"4\" data-y=\"24\" data-db-index=\"24\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-3C7NC\" data-order=\"G25-3C7NC\" >G25-3C7NC <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A25\" data-x=\"0\" data-y=\"25\" data-db-index=\"25\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B25\" data-x=\"1\" data-y=\"25\" data-db-index=\"25\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C25\" data-x=\"2\" data-y=\"25\" data-db-index=\"25\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"PNP\" data-order=\"PNP\" data-colspan=\"1\" data-rowspan=\"3\" >PNP <\/td><td data-cell-id=\"D25\" data-x=\"3\" data-y=\"25\" data-db-index=\"25\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NO\" data-order=\"NO\" >NO <\/td><td data-cell-id=\"E25\" data-x=\"4\" data-y=\"25\" data-db-index=\"25\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-3C7PA\" data-order=\"G25-3C7PA\" >G25-3C7PA <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A26\" data-x=\"0\" data-y=\"26\" data-db-index=\"26\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B26\" data-x=\"1\" data-y=\"26\" data-db-index=\"26\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C26\" data-x=\"2\" data-y=\"26\" data-db-index=\"26\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D26\" data-x=\"3\" data-y=\"26\" data-db-index=\"26\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NC\" data-order=\"NC\" >NC <\/td><td data-cell-id=\"E26\" data-x=\"4\" data-y=\"26\" data-db-index=\"26\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-3C7PB\" data-order=\"G25-3C7PB\" >G25-3C7PB <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A27\" data-x=\"0\" data-y=\"27\" data-db-index=\"27\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B27\" data-x=\"1\" data-y=\"27\" data-db-index=\"27\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C27\" data-x=\"2\" data-y=\"27\" data-db-index=\"27\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D27\" data-x=\"3\" data-y=\"27\" data-db-index=\"27\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NO+NC\" data-order=\"NO+NC\" >NO+NC <\/td><td data-cell-id=\"E27\" data-x=\"4\" data-y=\"27\" data-db-index=\"27\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-3C7PC\" data-order=\"G25-3C7PC\" >G25-3C7PC <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A28\" data-x=\"0\" data-y=\"28\" data-db-index=\"28\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B28\" data-x=\"1\" data-y=\"28\" data-db-index=\"28\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"90-250VAC\" data-order=\"90-250VAC\" data-colspan=\"1\" data-rowspan=\"3\" >90-250VAC <\/td><td data-cell-id=\"C28\" data-x=\"2\" data-y=\"28\" data-db-index=\"28\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"Controllable silicon\" data-order=\"Controllable silicon\" data-colspan=\"1\" data-rowspan=\"2\" >Controllable silicon <\/td><td data-cell-id=\"D28\" data-x=\"3\" data-y=\"28\" data-db-index=\"28\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"NO\" data-order=\"NO\" >NO <\/td><td data-cell-id=\"E28\" data-x=\"4\" data-y=\"28\" data-db-index=\"28\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-2C7LA\" data-order=\"G25-2C7LA\" >G25-2C7LA <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A29\" data-x=\"0\" data-y=\"29\" data-db-index=\"29\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B29\" data-x=\"1\" data-y=\"29\" data-db-index=\"29\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C29\" data-x=\"2\" data-y=\"29\" data-db-index=\"29\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D29\" data-x=\"3\" data-y=\"29\" data-db-index=\"29\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"NC\" data-order=\"NC\" >NC <\/td><td data-cell-id=\"E29\" data-x=\"4\" data-y=\"29\" data-db-index=\"29\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"G25-2C7LB\" data-order=\"G25-2C7LB\" >G25-2C7LB <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A30\" data-x=\"0\" data-y=\"30\" data-db-index=\"30\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"B30\" data-x=\"1\" data-y=\"30\" data-db-index=\"30\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C30\" data-x=\"2\" data-y=\"30\" data-db-index=\"30\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"Relay output\" data-order=\"Relay output\" data-colspan=\"2\" data-rowspan=\"1\" >Relay output <\/td><td data-cell-id=\"D30\" data-x=\"3\" data-y=\"30\" data-db-index=\"30\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E30\" data-x=\"4\" data-y=\"30\" data-db-index=\"30\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"G25-2C7JC\" data-order=\"G25-2C7JC\" >G25-2C7JC <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A31\" data-x=\"0\" data-y=\"31\" data-db-index=\"31\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"DC\/AC\/Control output\" data-order=\"DC\/AC\/Control output\" data-colspan=\"4\" data-rowspan=\"1\" >DC\/AC\/Control output <\/td><td data-cell-id=\"B31\" data-x=\"1\" data-y=\"31\" data-db-index=\"31\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C31\" data-x=\"2\" data-y=\"31\" data-db-index=\"31\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D31\" data-x=\"3\" data-y=\"31\" data-db-index=\"31\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E31\" data-x=\"4\" data-y=\"31\" data-db-index=\"31\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"DC:200mA\/AC:300mA\/relay:2A\" data-order=\"DC:200mA\/AC:300mA\/relay:2A\" >DC:200mA\/AC:300mA\/relay:2A <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A32\" data-x=\"0\" data-y=\"32\" data-db-index=\"32\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"DC\/AC Consumption current\" data-order=\"DC\/AC Consumption current\" data-colspan=\"4\" data-rowspan=\"1\" >DC\/AC Consumption current <\/td><td data-cell-id=\"B32\" data-x=\"1\" data-y=\"32\" data-db-index=\"32\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C32\" data-x=\"2\" data-y=\"32\" data-db-index=\"32\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D32\" data-x=\"3\" data-y=\"32\" data-db-index=\"32\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E32\" data-x=\"4\" data-y=\"32\" data-db-index=\"32\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"DC&lt;15mA AC&lt;10mA\" data-order=\"DC&lt;15mA AC&lt;10mA\" >DC<15mA AC<10mA <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A33\" data-x=\"0\" data-y=\"33\" data-db-index=\"33\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"DC\/AC Response time\" data-order=\"DC\/AC Response time\" data-colspan=\"4\" data-rowspan=\"1\" >DC\/AC Response time <\/td><td data-cell-id=\"B33\" data-x=\"1\" data-y=\"33\" data-db-index=\"33\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C33\" data-x=\"2\" data-y=\"33\" data-db-index=\"33\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D33\" data-x=\"3\" data-y=\"33\" data-db-index=\"33\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E33\" data-x=\"4\" data-y=\"33\" data-db-index=\"33\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"DC\uff1c2ms\/AC\uff1c20ms\" data-order=\"DC\uff1c2ms\/AC\uff1c20ms\" >DC\uff1c2ms\/AC\uff1c20ms <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A34\" data-x=\"0\" data-y=\"34\" data-db-index=\"34\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"Directional angel\" data-order=\"Directional angel\" data-colspan=\"4\" data-rowspan=\"1\" >Directional angel <\/td><td data-cell-id=\"B34\" data-x=\"1\" data-y=\"34\" data-db-index=\"34\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C34\" data-x=\"2\" data-y=\"34\" data-db-index=\"34\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D34\" data-x=\"3\" data-y=\"34\" data-db-index=\"34\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E34\" data-x=\"4\" data-y=\"34\" data-db-index=\"34\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"3\u00b0-10\u00b0\" data-order=\"3\u00b0-10\u00b0\" >3\u00b0-10\u00b0 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A35\" data-x=\"0\" data-y=\"35\" data-db-index=\"35\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"Detected object\" data-order=\"Detected object\" data-colspan=\"4\" data-rowspan=\"1\" >Detected object <\/td><td data-cell-id=\"B35\" data-x=\"1\" data-y=\"35\" data-db-index=\"35\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C35\" data-x=\"2\" data-y=\"35\" data-db-index=\"35\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D35\" data-x=\"3\" data-y=\"35\" data-db-index=\"35\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E35\" data-x=\"4\" data-y=\"35\" data-db-index=\"35\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"transparent or opaque body\" data-order=\"transparent or opaque body\" >transparent or opaque body <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A36\" data-x=\"0\" data-y=\"36\" data-db-index=\"36\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"Working environment temperature\" data-order=\"Working environment temperature\" data-colspan=\"4\" data-rowspan=\"1\" >Working environment temperature <\/td><td data-cell-id=\"B36\" data-x=\"1\" data-y=\"36\" data-db-index=\"36\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C36\" data-x=\"2\" data-y=\"36\" data-db-index=\"36\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D36\" data-x=\"3\" data-y=\"36\" data-db-index=\"36\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E36\" data-x=\"4\" data-y=\"36\" data-db-index=\"36\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"-25\u2103-+55\u2103\" data-order=\"-25\u2103-+55\u2103\" >-25\u2103-+55\u2103 <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A37\" data-x=\"0\" data-y=\"37\" data-db-index=\"37\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"Intensity of illumination working environment\" data-order=\"Intensity of illumination working environment\" data-colspan=\"4\" data-rowspan=\"1\" >Intensity of illumination working environment <\/td><td data-cell-id=\"B37\" data-x=\"1\" data-y=\"37\" data-db-index=\"37\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C37\" data-x=\"2\" data-y=\"37\" data-db-index=\"37\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D37\" data-x=\"3\" data-y=\"37\" data-db-index=\"37\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E37\" data-x=\"4\" data-y=\"37\" data-db-index=\"37\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"Sunlight under 10000LX incandescent lamp under 3000LX\" data-order=\"Sunlight under 10000LX incandescent lamp under 3000LX\" >Sunlight under 10000LX incandescent lamp under 3000LX <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A38\" data-x=\"0\" data-y=\"38\" data-db-index=\"38\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"Shell material\" data-order=\"Shell material\" data-colspan=\"4\" data-rowspan=\"1\" >Shell material <\/td><td data-cell-id=\"B38\" data-x=\"1\" data-y=\"38\" data-db-index=\"38\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C38\" data-x=\"2\" data-y=\"38\" data-db-index=\"38\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D38\" data-x=\"3\" data-y=\"38\" data-db-index=\"38\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E38\" data-x=\"4\" data-y=\"38\" data-db-index=\"38\" class=\"htCenter htMiddle\" data-cell-type=\"text\" data-original-value=\"ABS resein\" data-order=\"ABS resein\" >ABS resein <\/td><\/tr><tr style=\"height:px\" ><td data-cell-id=\"A39\" data-x=\"0\" data-y=\"39\" data-db-index=\"39\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"Protection grade\" data-order=\"Protection grade\" data-colspan=\"4\" data-rowspan=\"1\" >Protection grade <\/td><td data-cell-id=\"B39\" data-x=\"1\" data-y=\"39\" data-db-index=\"39\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"C39\" data-x=\"2\" data-y=\"39\" data-db-index=\"39\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"D39\" data-x=\"3\" data-y=\"39\" data-db-index=\"39\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"\" data-order=\"\" data-hide=\"true\" ><\/td><td data-cell-id=\"E39\" data-x=\"4\" data-y=\"39\" data-db-index=\"39\" class=\"htCenter htMiddle bg-c7c7c7\" data-cell-type=\"text\" data-original-value=\"IP67\" data-order=\"IP67\" >IP67 <\/td><\/tr><\/tbody><\/table><!-- \/#supsystic-table-98.supsystic-table --><\/div><!-- \/.supsystic-tables-wrap --><!-- Tables Generator by Supsystic --><!-- Version:1.11.1 --><!-- http:\/\/supsystic.com\/ --><a title=\"WordPress Data Table Plugin\" style=\"display:none;\" href=\"https:\/\/supsystic.com\/plugins\/wordpress-data-table-plugin\/?utm_medium=love_link\" target=\"_blank\">WordPress Data Table Plugin<\/a>\n","protected":false},"excerpt":{"rendered":"<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Distancia m\u00e1xima de detecci\u00f3n de 70 cm,<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">PNP y NPN disponibles,<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Est\u00e1n disponibles NO, NC o NO+NC,<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Utiliza 2 metros de cable con n\u00facleo de cobre de alta resistencia,<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">2 a\u00f1os de garant\u00eda, calidad fiable<\/span><\/li>\n<\/ol>","protected":false},"featured_media":7758,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[158,107],"product_tag":[],"class_list":{"0":"post-7759","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-photoelectric-sensor","7":"product_cat-proximity-sensor","8":"desktop-align-center","9":"tablet-align-left","10":"mobile-align-left","12":"first","13":"instock","14":"shipping-taxable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Diffuse Photoelectric Sensor<\/title>\n<meta name=\"description\" content=\"Lorentzzi G25 diffuse photoelectric sensor has 70 cm detecting distance and is suitable for detecting any kind of materials with ultra-high quality.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lorentzzi.com\/es\/products\/proximity-sensor\/sensor-fotoelectrico\/diffuse-photoelectric-sensor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diffuse Photoelectric Sensor\" \/>\n<meta property=\"og:description\" content=\"Lorentzzi G25 diffuse photoelectric sensor has 70 cm detecting distance and is suitable for detecting any kind of materials with ultra-high quality.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lorentzzi.com\/es\/products\/proximity-sensor\/sensor-fotoelectrico\/diffuse-photoelectric-sensor\/\" \/>\n<meta property=\"og:site_name\" content=\"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-27T05:14:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/04\/G25-photoelectric-sensor-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/products\\\/proximity-sensor\\\/photoelectric-sensor\\\/diffuse-photoelectric-sensor\\\/\",\"url\":\"https:\\\/\\\/lorentzzi.com\\\/products\\\/proximity-sensor\\\/photoelectric-sensor\\\/diffuse-photoelectric-sensor\\\/\",\"name\":\"Diffuse Photoelectric Sensor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/products\\\/proximity-sensor\\\/photoelectric-sensor\\\/diffuse-photoelectric-sensor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/products\\\/proximity-sensor\\\/photoelectric-sensor\\\/diffuse-photoelectric-sensor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lorentzzi.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/G25-photoelectric-sensor-1.jpg\",\"datePublished\":\"2023-04-10T13:52:09+00:00\",\"dateModified\":\"2025-12-27T05:14:01+00:00\",\"description\":\"Lorentzzi G25 diffuse photoelectric sensor has 70 cm detecting distance and is suitable for detecting any kind of materials with ultra-high quality.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/products\\\/proximity-sensor\\\/photoelectric-sensor\\\/diffuse-photoelectric-sensor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lorentzzi.com\\\/products\\\/proximity-sensor\\\/photoelectric-sensor\\\/diffuse-photoelectric-sensor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/products\\\/proximity-sensor\\\/photoelectric-sensor\\\/diffuse-photoelectric-sensor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lorentzzi.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/G25-photoelectric-sensor-1.jpg\",\"contentUrl\":\"https:\\\/\\\/lorentzzi.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/G25-photoelectric-sensor-1.jpg\",\"width\":640,\"height\":640,\"caption\":\"G25 diffuse photoelectric sensor-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/products\\\/proximity-sensor\\\/photoelectric-sensor\\\/diffuse-photoelectric-sensor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lorentzzi.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/lorentzzi.com\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diffuse Photoelectric Sensor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#website\",\"url\":\"https:\\\/\\\/lorentzzi.com\\\/\",\"name\":\"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter\",\"description\":\"Lorentzzi supply temperature controller, SSR, proximity sensor, SCR power regulator and timer switch with good quality and affordable prices.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lorentzzi.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#organization\",\"name\":\"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter\",\"url\":\"https:\\\/\\\/lorentzzi.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lorentzzi.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Lorenz-Electric-Company-Logo.png\",\"contentUrl\":\"https:\\\/\\\/lorentzzi.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Lorenz-Electric-Company-Logo.png\",\"width\":350,\"height\":100,\"caption\":\"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter\"},\"image\":{\"@id\":\"https:\\\/\\\/lorentzzi.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Barrera fotoel\u00e9ctrica difusa","description":"El sensor fotoel\u00e9ctrico difuso Lorentzzi G25 tiene una distancia de detecci\u00f3n de 70 cm y es adecuado para detectar cualquier tipo de material con una calidad ultra alta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lorentzzi.com\/es\/products\/proximity-sensor\/sensor-fotoelectrico\/diffuse-photoelectric-sensor\/","og_locale":"es_ES","og_type":"article","og_title":"Diffuse Photoelectric Sensor","og_description":"Lorentzzi G25 diffuse photoelectric sensor has 70 cm detecting distance and is suitable for detecting any kind of materials with ultra-high quality.","og_url":"https:\/\/lorentzzi.com\/es\/products\/proximity-sensor\/sensor-fotoelectrico\/diffuse-photoelectric-sensor\/","og_site_name":"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter","article_modified_time":"2025-12-27T05:14:01+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/04\/G25-photoelectric-sensor-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lorentzzi.com\/products\/proximity-sensor\/photoelectric-sensor\/diffuse-photoelectric-sensor\/","url":"https:\/\/lorentzzi.com\/products\/proximity-sensor\/photoelectric-sensor\/diffuse-photoelectric-sensor\/","name":"Barrera fotoel\u00e9ctrica difusa","isPartOf":{"@id":"https:\/\/lorentzzi.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lorentzzi.com\/products\/proximity-sensor\/photoelectric-sensor\/diffuse-photoelectric-sensor\/#primaryimage"},"image":{"@id":"https:\/\/lorentzzi.com\/products\/proximity-sensor\/photoelectric-sensor\/diffuse-photoelectric-sensor\/#primaryimage"},"thumbnailUrl":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/04\/G25-photoelectric-sensor-1.jpg","datePublished":"2023-04-10T13:52:09+00:00","dateModified":"2025-12-27T05:14:01+00:00","description":"El sensor fotoel\u00e9ctrico difuso Lorentzzi G25 tiene una distancia de detecci\u00f3n de 70 cm y es adecuado para detectar cualquier tipo de material con una calidad ultra alta.","breadcrumb":{"@id":"https:\/\/lorentzzi.com\/products\/proximity-sensor\/photoelectric-sensor\/diffuse-photoelectric-sensor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lorentzzi.com\/products\/proximity-sensor\/photoelectric-sensor\/diffuse-photoelectric-sensor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lorentzzi.com\/products\/proximity-sensor\/photoelectric-sensor\/diffuse-photoelectric-sensor\/#primaryimage","url":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/04\/G25-photoelectric-sensor-1.jpg","contentUrl":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2023\/04\/G25-photoelectric-sensor-1.jpg","width":640,"height":640,"caption":"G25 diffuse photoelectric sensor-1"},{"@type":"BreadcrumbList","@id":"https:\/\/lorentzzi.com\/products\/proximity-sensor\/photoelectric-sensor\/diffuse-photoelectric-sensor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lorentzzi.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/lorentzzi.com\/products\/"},{"@type":"ListItem","position":3,"name":"Diffuse Photoelectric Sensor"}]},{"@type":"WebSite","@id":"https:\/\/lorentzzi.com\/#website","url":"https:\/\/lorentzzi.com\/","name":"Lorentzzi Industrial Supply-Fabricante y exportador chino","description":"Lorentzzi suministra controlador de temperatura, SSR, sensor de proximidad, regulador de potencia SCR e interruptor temporizador con buena calidad y precios asequibles.","publisher":{"@id":"https:\/\/lorentzzi.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lorentzzi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lorentzzi.com\/#organization","name":"Lorentzzi Industrial Supply-Fabricante y exportador chino","url":"https:\/\/lorentzzi.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lorentzzi.com\/#\/schema\/logo\/image\/","url":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2021\/07\/Lorenz-Electric-Company-Logo.png","contentUrl":"https:\/\/lorentzzi.com\/wp-content\/uploads\/2021\/07\/Lorenz-Electric-Company-Logo.png","width":350,"height":100,"caption":"Lorentzzi Industrial Supply-Chinese Manufacturer&amp;Exporter"},"image":{"@id":"https:\/\/lorentzzi.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lorentzzi.com\/es\/wp-json\/wp\/v2\/product\/7759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lorentzzi.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lorentzzi.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":7,"href":"https:\/\/lorentzzi.com\/es\/wp-json\/wp\/v2\/product\/7759\/revisions"}],"predecessor-version":[{"id":13021,"href":"https:\/\/lorentzzi.com\/es\/wp-json\/wp\/v2\/product\/7759\/revisions\/13021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lorentzzi.com\/es\/wp-json\/wp\/v2\/media\/7758"}],"wp:attachment":[{"href":"https:\/\/lorentzzi.com\/es\/wp-json\/wp\/v2\/media?parent=7759"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lorentzzi.com\/es\/wp-json\/wp\/v2\/product_brand?post=7759"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lorentzzi.com\/es\/wp-json\/wp\/v2\/product_cat?post=7759"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lorentzzi.com\/es\/wp-json\/wp\/v2\/product_tag?post=7759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}